{"id":331398,"date":"2022-01-17T11:01:00","date_gmt":"2022-01-17T11:01:00","guid":{"rendered":"https:\/\/www.purejewels.com\/?p=331398"},"modified":"2025-04-21T09:55:11","modified_gmt":"2025-04-21T08:55:11","slug":"festerer-dollar-und-aussicht-auf-hohere-us-zinsen-setzen-gold-unter-druck","status":"publish","type":"post","link":"https:\/\/www.purejewels.com\/de\/gold-dips-pressured-by-firmer-dollar-and-prospects-for-higher-u-s-rates\/","title":{"rendered":"Gold gibt nach, unter Druck durch festeren Dollar und Aussicht auf h\u00f6here US-Zinsen"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"331398\" class=\"elementor elementor-331398\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-18d7e88 e-flex e-con-boxed e-con e-parent\" data-id=\"18d7e88\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-917d9bb elementor-widget elementor-widget-text-editor\" data-id=\"917d9bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Mitte Januar gab der Goldpreis nach, was auf einen festeren Dollar und die Erwartung zur\u00fcckzuf\u00fchren war, dass die US-Zinsen steigen k\u00f6nnten, um die Inflation einzud\u00e4mmen.<\/p><p>Gold gab am 14. Januar um 0,3 Prozent auf $1.816,22 je Unze nach, belastet durch einen st\u00e4rkeren Dollar und festere Treasury-Renditen aufgrund der Aussicht auf US-Zinserh\u00f6hungen. Der Aufw\u00e4rtstrend des Greenback macht\u00a0<strong>auf Dollar lautendes Gold<\/strong>\u00a0teurer in Bezug auf andere W\u00e4hrungen.<\/p><p>Die US-Wirtschaft erlebt eine Inflation wie seit Jahrzehnten nicht mehr.<\/p><p>Dies ist f\u00fcr Gold relevant, da die US-M\u00e4rkte einen gro\u00dfen Einfluss auf den Goldpreis haben.<\/p><p>Wirtschaftswissenschaftler sehen die Gefahr, dass die Verbraucherpreisinflation in den USA von derzeit rund 7 Prozent auf Jahresbasis ansteigen k\u00f6nnte.<\/p><p>\"Es besteht die Sorge, dass die\u00a0<a href=\"https:\/\/www.purejewels.com\/de\/gold-stieg-in-der-zweiten-aprilwoche-dank-des-status-als-sicherer-hafen\/\">U.S. Federal Reserve<\/a>\u00a0k\u00f6nnte die Zinss\u00e4tze verst\u00e4rkt anheben, um die Inflation zu kontrollieren\", schrieb Lawrie Williams,\u00a0<a href=\"https:\/\/www.purejewels.com\/de\/gold-steigt-nach-beschluss-der-us-zentralbank-die-stimulierung-zu-reduzieren-britische-zinserhohung-starkt-pfund\/\">Goldmarkt<\/a>\u00a0Kommentator beim Edelmetallh\u00e4ndler Sharps Pixley.<\/p><p>Steigende US-Zinsen k\u00f6nnen dazu f\u00fchren, dass Goldbarren ohne Rendite f\u00fcr Anleger weniger attraktiv werden.<\/p><p>\"\u00dcber den Erwartungen liegende Anstiege k\u00f6nnten die Konjunktur vor\u00fcbergehend d\u00e4mpfen\u00a0<strong><a href=\"https:\/\/www.purejewels.com\/de\/gold-gibt-nach-berichten-uber-die-ruckkehr-einiger-russischer-truppen-in-der-ukraine-in-ihre-stutzpunkte-nach\/\">Goldpreis<\/a><\/strong>.  Bisher war die Fed jedoch eher vorsichtig bei der Umsetzung von Ma\u00dfnahmen, die das US-Wirtschaftswachstum beeintr\u00e4chtigen k\u00f6nnten, und sie kann vielleicht noch etwas l\u00e4nger mit einem hohen Inflationsniveau leben\", schrieb Williams.<\/p><p>Die Aussichten f\u00fcr den Goldpreis haben sich in der dritten Woche des neuen Jahres verbessert, schreibt Kitco News-Korrespondentin Anna Golubova.<\/p><p>\"Analysten w\u00e4gen die Folgen eines m\u00f6glichen geldpolitischen Fehlers ab, da die <a href=\"https:\/\/www.purejewels.com\/de\/gold-rose-in-second-week-of-april-buoyed-by-safe-haven-status\/\">U.S. Federal Reserve<\/a> (Zentralbank) in Anbetracht der j\u00fcngsten Inflationsdaten eine restriktivere Haltung einnimmt\", schrieb sie.<\/p><p>\"Die beiden wichtigsten Daten, die die M\u00e4rkte in einer risikoarmen Stimmung halten, sind die Inflation und die Einzelhandelsums\u00e4tze. In den USA war die Inflation im Dezember so hoch wie seit 1982 nicht mehr\", f\u00fcgte sie hinzu. \"Die Einzelhandelsums\u00e4tze waren mit einem Minus von 1,9% so stark r\u00fcckl\u00e4ufig wie seit 10 Monaten nicht mehr.<\/p><p>Die Einzelhandelsums\u00e4tze gingen zur\u00fcck, da die Amerikaner aufgrund von Engp\u00e4ssen in der Lieferkette und einer explosionsartigen Zunahme von COVID-19-Infektionen mit einem Mangel an Waren zu k\u00e4mpfen hatten.<\/p><p>Nach Ansicht von Wirtschaftsexperten werden der US-Dollar und die Anleiherenditen die beiden wichtigsten Treiber f\u00fcr Gold sein.<\/p><p>F\u00fcr\u00a0<strong>Britische Goldsparer<\/strong>Das Pfund scheint gegen\u00fcber dem Dollar weiterhin gut gest\u00fctzt zu sein, da Wirtschaftsexperten mit weiteren Zinserh\u00f6hungen der Bank of England in diesem Jahr rechnen, um die Inflation unter Kontrolle zu halten. Ein st\u00e4rkeres Pfund w\u00fcrde den Kauf von in Dollar denominiertem Gold erschwinglicher machen.<\/p><p>Einige \u00d6konomen sehen die M\u00f6glichkeit einer Anhebung um 25 Basispunkte auf der Februar-Sitzung der Zentralbank.<\/p><p>Die m\u00f6gliche Abl\u00f6sung von Premierminister Boris Johnson an der Spitze der Regierung k\u00f6nnte das Pfund weiter st\u00fctzen, da m\u00f6gliche Nachfolger wie Kanzler Rishi Sunak oder Au\u00dfenministerin Liz Truss einen ruhigeren, weniger sprunghaften Ansatz in die Regierung einbringen k\u00f6nnten, so einige Marktkommentatoren.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Mitte Januar rutschte der Goldpreis ab, was auf einen festeren Dollar und die Erwartung zur\u00fcckzuf\u00fchren war, dass die US-Zinsen steigen k\u00f6nnten, um die<\/p>","protected":false},"author":173,"featured_media":362634,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","_crsspst_to_jayantr4sg-hostcom":false,"footnotes":""},"categories":[1876],"tags":[],"class_list":["post-331398","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gold-reports"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Read Gold Report: Gold slipped in mid-January 2022<\/title>\n<meta name=\"description\" content=\"Gold slipped in mid-January, pressured by a firmer dollar &amp; sentiment that U.S. interest rates could rise in order to tame inflation\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.purejewels.com\/de\/festerer-dollar-und-aussicht-auf-hohere-us-zinsen-setzen-gold-unter-druck\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Read Gold Report: Gold slipped in mid-January 2022\" \/>\n<meta property=\"og:description\" content=\"Gold slipped in mid-January, pressured by a firmer dollar &amp; sentiment that U.S. interest rates could rise in order to tame inflation\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.purejewels.com\/de\/festerer-dollar-und-aussicht-auf-hohere-us-zinsen-setzen-gold-unter-druck\/\" \/>\n<meta property=\"og:site_name\" content=\"PureJewels UK\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-17T11:01:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-21T08:55:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.purejewels.com\/wp-content\/uploads\/2024\/04\/Gold-Market-Commentary-1-01-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"930\" \/>\n\t<meta property=\"og:image:height\" content=\"604\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Anupama Jha\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Anupama Jha\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.purejewels.com\\\/gold-dips-pressured-by-firmer-dollar-and-prospects-for-higher-u-s-rates\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.purejewels.com\\\/gold-dips-pressured-by-firmer-dollar-and-prospects-for-higher-u-s-rates\\\/\"},\"author\":{\"name\":\"Anupama Jha\",\"@id\":\"https:\\\/\\\/www.purejewels.com\\\/#\\\/schema\\\/person\\\/38252805a75b9d895b6b4e0a6dd6e164\"},\"headline\":\"Gold dips, pressured by firmer dollar and prospects for higher U.S. rates\",\"datePublished\":\"2022-01-17T11:01:00+00:00\",\"dateModified\":\"2025-04-21T08:55:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.purejewels.com\\\/gold-dips-pressured-by-firmer-dollar-and-prospects-for-higher-u-s-rates\\\/\"},\"wordCount\":455,\"publisher\":{\"@id\":\"https:\\\/\\\/www.purejewels.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.purejewels.com\\\/gold-dips-pressured-by-firmer-dollar-and-prospects-for-higher-u-s-rates\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/static.purejewels.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Gold-Market-Commentary-1-01-1.jpg\",\"articleSection\":[\"Gold Reports\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.purejewels.com\\\/gold-dips-pressured-by-firmer-dollar-and-prospects-for-higher-u-s-rates\\\/\",\"url\":\"https:\\\/\\\/www.purejewels.com\\\/gold-dips-pressured-by-firmer-dollar-and-prospects-for-higher-u-s-rates\\\/\",\"name\":\"Read Gold Report: Gold slipped in mid-January 2022\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.purejewels.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.purejewels.com\\\/gold-dips-pressured-by-firmer-dollar-and-prospects-for-higher-u-s-rates\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.purejewels.com\\\/gold-dips-pressured-by-firmer-dollar-and-prospects-for-higher-u-s-rates\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/static.purejewels.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Gold-Market-Commentary-1-01-1.jpg\",\"datePublished\":\"2022-01-17T11:01:00+00:00\",\"dateModified\":\"2025-04-21T08:55:11+00:00\",\"description\":\"Gold slipped in mid-January, pressured by a firmer dollar & sentiment that U.S. interest rates could rise in order to tame inflation\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.purejewels.com\\\/gold-dips-pressured-by-firmer-dollar-and-prospects-for-higher-u-s-rates\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.purejewels.com\\\/gold-dips-pressured-by-firmer-dollar-and-prospects-for-higher-u-s-rates\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.purejewels.com\\\/gold-dips-pressured-by-firmer-dollar-and-prospects-for-higher-u-s-rates\\\/#primaryimage\",\"url\":\"https:\\\/\\\/static.purejewels.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Gold-Market-Commentary-1-01-1.jpg\",\"contentUrl\":\"https:\\\/\\\/static.purejewels.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Gold-Market-Commentary-1-01-1.jpg\",\"width\":930,\"height\":604,\"caption\":\"Gold-Market Commentary\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.purejewels.com\\\/gold-dips-pressured-by-firmer-dollar-and-prospects-for-higher-u-s-rates\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.purejewels.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gold dips, pressured by firmer dollar and prospects for higher U.S. rates\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.purejewels.com\\\/#website\",\"url\":\"https:\\\/\\\/www.purejewels.com\\\/\",\"name\":\"PureJewels UK\",\"description\":\"Share the Love\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.purejewels.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.purejewels.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.purejewels.com\\\/#organization\",\"name\":\"PureJewels UK\",\"url\":\"https:\\\/\\\/www.purejewels.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.purejewels.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/static.purejewels.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Logo-PJ-New-1.png\",\"contentUrl\":\"https:\\\/\\\/static.purejewels.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Logo-PJ-New-1.png\",\"width\":150,\"height\":80,\"caption\":\"PureJewels UK\"},\"image\":{\"@id\":\"https:\\\/\\\/www.purejewels.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.purejewels.com\\\/#\\\/schema\\\/person\\\/38252805a75b9d895b6b4e0a6dd6e164\",\"name\":\"Anupama Jha\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e7c55965159cdb5740d7f53c91cba89023f1c0d675ad340c73c9810fa4a2c1d1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e7c55965159cdb5740d7f53c91cba89023f1c0d675ad340c73c9810fa4a2c1d1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e7c55965159cdb5740d7f53c91cba89023f1c0d675ad340c73c9810fa4a2c1d1?s=96&d=mm&r=g\",\"caption\":\"Anupama Jha\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gold Report lesen: Gold rutschte Mitte Januar 2022 ab","description":"Gold gab Mitte Januar nach, unter dem Druck eines festeren Dollars und der Erwartung, dass die US-Zinsen steigen k\u00f6nnten, um die Inflation einzud\u00e4mmen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.purejewels.com\/de\/festerer-dollar-und-aussicht-auf-hohere-us-zinsen-setzen-gold-unter-druck\/","og_locale":"de_DE","og_type":"article","og_title":"Read Gold Report: Gold slipped in mid-January 2022","og_description":"Gold slipped in mid-January, pressured by a firmer dollar & sentiment that U.S. interest rates could rise in order to tame inflation","og_url":"https:\/\/www.purejewels.com\/de\/festerer-dollar-und-aussicht-auf-hohere-us-zinsen-setzen-gold-unter-druck\/","og_site_name":"PureJewels UK","article_published_time":"2022-01-17T11:01:00+00:00","article_modified_time":"2025-04-21T08:55:11+00:00","og_image":[{"width":930,"height":604,"url":"https:\/\/www.purejewels.com\/wp-content\/uploads\/2024\/04\/Gold-Market-Commentary-1-01-1.jpg","type":"image\/jpeg"}],"author":"Anupama Jha","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Anupama Jha","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.purejewels.com\/gold-dips-pressured-by-firmer-dollar-and-prospects-for-higher-u-s-rates\/#article","isPartOf":{"@id":"https:\/\/www.purejewels.com\/gold-dips-pressured-by-firmer-dollar-and-prospects-for-higher-u-s-rates\/"},"author":{"name":"Anupama Jha","@id":"https:\/\/www.purejewels.com\/#\/schema\/person\/38252805a75b9d895b6b4e0a6dd6e164"},"headline":"Gold dips, pressured by firmer dollar and prospects for higher U.S. rates","datePublished":"2022-01-17T11:01:00+00:00","dateModified":"2025-04-21T08:55:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.purejewels.com\/gold-dips-pressured-by-firmer-dollar-and-prospects-for-higher-u-s-rates\/"},"wordCount":455,"publisher":{"@id":"https:\/\/www.purejewels.com\/#organization"},"image":{"@id":"https:\/\/www.purejewels.com\/gold-dips-pressured-by-firmer-dollar-and-prospects-for-higher-u-s-rates\/#primaryimage"},"thumbnailUrl":"https:\/\/static.purejewels.com\/wp-content\/uploads\/2024\/04\/Gold-Market-Commentary-1-01-1.jpg","articleSection":["Gold Reports"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.purejewels.com\/gold-dips-pressured-by-firmer-dollar-and-prospects-for-higher-u-s-rates\/","url":"https:\/\/www.purejewels.com\/gold-dips-pressured-by-firmer-dollar-and-prospects-for-higher-u-s-rates\/","name":"Gold Report lesen: Gold rutschte Mitte Januar 2022 ab","isPartOf":{"@id":"https:\/\/www.purejewels.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.purejewels.com\/gold-dips-pressured-by-firmer-dollar-and-prospects-for-higher-u-s-rates\/#primaryimage"},"image":{"@id":"https:\/\/www.purejewels.com\/gold-dips-pressured-by-firmer-dollar-and-prospects-for-higher-u-s-rates\/#primaryimage"},"thumbnailUrl":"https:\/\/static.purejewels.com\/wp-content\/uploads\/2024\/04\/Gold-Market-Commentary-1-01-1.jpg","datePublished":"2022-01-17T11:01:00+00:00","dateModified":"2025-04-21T08:55:11+00:00","description":"Gold gab Mitte Januar nach, unter dem Druck eines festeren Dollars und der Erwartung, dass die US-Zinsen steigen k\u00f6nnten, um die Inflation einzud\u00e4mmen","breadcrumb":{"@id":"https:\/\/www.purejewels.com\/gold-dips-pressured-by-firmer-dollar-and-prospects-for-higher-u-s-rates\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.purejewels.com\/gold-dips-pressured-by-firmer-dollar-and-prospects-for-higher-u-s-rates\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.purejewels.com\/gold-dips-pressured-by-firmer-dollar-and-prospects-for-higher-u-s-rates\/#primaryimage","url":"https:\/\/static.purejewels.com\/wp-content\/uploads\/2024\/04\/Gold-Market-Commentary-1-01-1.jpg","contentUrl":"https:\/\/static.purejewels.com\/wp-content\/uploads\/2024\/04\/Gold-Market-Commentary-1-01-1.jpg","width":930,"height":604,"caption":"Gold-Market Commentary"},{"@type":"BreadcrumbList","@id":"https:\/\/www.purejewels.com\/gold-dips-pressured-by-firmer-dollar-and-prospects-for-higher-u-s-rates\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.purejewels.com\/"},{"@type":"ListItem","position":2,"name":"Gold dips, pressured by firmer dollar and prospects for higher U.S. rates"}]},{"@type":"WebSite","@id":"https:\/\/www.purejewels.com\/#website","url":"https:\/\/www.purejewels.com\/","name":"PureJewels UK","description":"Teile die Liebe","publisher":{"@id":"https:\/\/www.purejewels.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.purejewels.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.purejewels.com\/#organization","name":"PureJewels UK","url":"https:\/\/www.purejewels.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.purejewels.com\/#\/schema\/logo\/image\/","url":"https:\/\/static.purejewels.com\/wp-content\/uploads\/2020\/11\/Logo-PJ-New-1.png","contentUrl":"https:\/\/static.purejewels.com\/wp-content\/uploads\/2020\/11\/Logo-PJ-New-1.png","width":150,"height":80,"caption":"PureJewels UK"},"image":{"@id":"https:\/\/www.purejewels.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.purejewels.com\/#\/schema\/person\/38252805a75b9d895b6b4e0a6dd6e164","name":"Anupama Jha","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/e7c55965159cdb5740d7f53c91cba89023f1c0d675ad340c73c9810fa4a2c1d1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e7c55965159cdb5740d7f53c91cba89023f1c0d675ad340c73c9810fa4a2c1d1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e7c55965159cdb5740d7f53c91cba89023f1c0d675ad340c73c9810fa4a2c1d1?s=96&d=mm&r=g","caption":"Anupama Jha"}}]}},"_links":{"self":[{"href":"https:\/\/www.purejewels.com\/de\/wp-json\/wp\/v2\/posts\/331398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.purejewels.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.purejewels.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.purejewels.com\/de\/wp-json\/wp\/v2\/users\/173"}],"replies":[{"embeddable":true,"href":"https:\/\/www.purejewels.com\/de\/wp-json\/wp\/v2\/comments?post=331398"}],"version-history":[{"count":3,"href":"https:\/\/www.purejewels.com\/de\/wp-json\/wp\/v2\/posts\/331398\/revisions"}],"predecessor-version":[{"id":393277,"href":"https:\/\/www.purejewels.com\/de\/wp-json\/wp\/v2\/posts\/331398\/revisions\/393277"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.purejewels.com\/de\/wp-json\/wp\/v2\/media\/362634"}],"wp:attachment":[{"href":"https:\/\/www.purejewels.com\/de\/wp-json\/wp\/v2\/media?parent=331398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.purejewels.com\/de\/wp-json\/wp\/v2\/categories?post=331398"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.purejewels.com\/de\/wp-json\/wp\/v2\/tags?post=331398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}